{"id":241343,"date":"2020-12-11T14:18:06","date_gmt":"2020-12-11T14:18:06","guid":{"rendered":"https:\/\/italianacontenitori.com\/product\/roll-72-x-80-cm-base-reforzada\/"},"modified":"2026-07-02T08:18:21","modified_gmt":"2026-07-02T08:18:21","slug":"roll-72-x-80-cm-base-renforzada","status":"publish","type":"product","link":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/","title":{"rendered":"Contenedor de rollo est\u00e1ndar 72 x 80 cm &#8211; Reforzado"},"content":{"rendered":"<p>El contenedor rodante est\u00e1ndar de 72 x 80 cm con base reforzada es un carro de malla met\u00e1lica con ruedas dise\u00f1ado para garantizar la manipulaci\u00f3n y el almacenamiento m\u00e1s eficaces de mercanc\u00edas en entornos muy transitados, como <strong>lavander\u00edas industriales, hospitales y comunidades<\/strong>. Este robusto carro para paquetes ofrece resistencia y estabilidad, con una capacidad de carga de hasta 600 kg, perfecta para transportar mercanc\u00edas voluminosas y pesadas. <strong>Los refuerzos en las esquinas de la base proporcionan resistencia adicional<\/strong>, por lo que es ideal para un uso intensivo, incluso en una configuraci\u00f3n de dos lados con el uso de correas.  <\/p>\n<h2>Carro industrial <strong>est\u00e1ndar con base reforzada<\/strong> 72&#215;80 cm de un vistazo:<\/h2>\n<ul>\n<li><strong>Dimensiones exteriores:<\/strong> 72 x 80 cm<\/li>\n<li><strong>Altura:<\/strong> de 152 a 180 cm<\/li>\n<li><strong>Capacidad de carga:<\/strong> 400 kg o 600 kg seg\u00fan las ruedas elegidas<\/li>\n<li><strong>Malla de base ajustada<\/strong>: evita que se caigan los objetos peque\u00f1os.<\/li>\n<\/ul>\n<h2>Ra\u00edles laterales, malla, ruedas y otras caracter\u00edsticas<\/h2>\n<p>El portacargas con base reforzada est\u00e1 disponible en distintas configuraciones de <strong>aparador: 2, 3 \u00f3 4 con trampilla<\/strong> para facilitar la carga y descarga de mercanc\u00edas. Su robusta estructura se complementa con una malla de 105&#215;155 mm y 380&#215;395 mm, que garantiza la m\u00e1xima seguridad durante el transporte. Las ruedas de gran resistencia, que pueden configurarse con opciones fijas o giratorias, garantizan una excelente maniobrabilidad incluso con cargas pesadas, lo que la hace ideal para su uso en sectores como la restauraci\u00f3n y la manipulaci\u00f3n de residuos y cart\u00f3n.  <\/p>\n<p><strong>Env\u00edo:<\/strong> un <strong>rollo<\/strong> completamente montado contiene hasta 4 unidades desmontadas en su interior, lo que permite <strong>enviar 5 contenedores de rollo est\u00e1ndar en el espacio de uno,<\/strong> reduciendo los costes de transporte y devoluci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roll container cl\u00e1sico apto para cualquier uso. Disponible en varias alturas y configuraciones para gestionar mejor el almacenamiento y el transporte de mercanc\u00edas. La base de esquinas reforzadas asegura una mayor resistencia.<\/p>\n","protected":false},"featured_media":240273,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1548],"product_tag":[2127],"class_list":["post-241343","product","type-product","status-publish","has-post-thumbnail","product_cat-roll-container-es","product_tag-roll-container-dimensiones-estandar","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contenedor de rollo est\u00e1ndar 72 x 80 cm - Reforzado - italianacontenitori.com<\/title>\n<meta name=\"description\" content=\"Contenedor rodante est\u00e1ndar con base reforzada. Robustez y estabilidad para mercanc\u00edas pesadas, ideal para lavander\u00edas, industria, gran distribuci\u00f3n. Carga m\u00e1xima: 600 kg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contenedor de rollo est\u00e1ndar 72 x 80 cm - Reforzado - italianacontenitori.com\" \/>\n<meta property=\"og:description\" content=\"Contenedor rodante est\u00e1ndar con base reforzada. Robustez y estabilidad para mercanc\u00edas pesadas, ideal para lavander\u00edas, industria, gran distribuci\u00f3n. Carga m\u00e1xima: 600 kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/\" \/>\n<meta property=\"og:site_name\" content=\"italianacontenitori.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T08:18:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/12\/ROLR0050H4R0-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/\",\"name\":\"Contenedor de rollo est\u00e1ndar 72 x 80 cm - Reforzado - italianacontenitori.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ROLR0050H4R0-1.png\",\"datePublished\":\"2020-12-11T14:18:06+00:00\",\"dateModified\":\"2026-07-02T08:18:21+00:00\",\"description\":\"Contenedor rodante est\u00e1ndar con base reforzada. Robustez y estabilidad para mercanc\u00edas pesadas, ideal para lavander\u00edas, industria, gran distribuci\u00f3n. Carga m\u00e1xima: 600 kg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ROLR0050H4R0-1.png\",\"contentUrl\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ROLR0050H4R0-1.png\",\"width\":1024,\"height\":1024,\"caption\":\"Contenedor rodante est\u00e1ndar con base reforzada. 72x80 cm. Disponible con 2 lados, 3 lados y 4 lados con solapa. Capacidad de carga 600 kg.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/producto\\\/roll-72-x-80-cm-base-renforzada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo Espa\u00f1ol\",\"item\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/cataogo-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Contenedor de rollo est\u00e1ndar 72 x 80 cm &#8211; Reforzado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/\",\"name\":\"italianacontenitori.com\",\"description\":\"Produzione di contenitori industriali e roll container\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/#organization\",\"name\":\"Italiana Contenitori s.r.l.\",\"alternateName\":\"IC\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-Logo-Italiana-Contenitori_favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-Logo-Italiana-Contenitori_favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Italiana Contenitori s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contenedor de rollo est\u00e1ndar 72 x 80 cm - Reforzado - italianacontenitori.com","description":"Contenedor rodante est\u00e1ndar con base reforzada. Robustez y estabilidad para mercanc\u00edas pesadas, ideal para lavander\u00edas, industria, gran distribuci\u00f3n. Carga m\u00e1xima: 600 kg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/","og_locale":"es_ES","og_type":"article","og_title":"Contenedor de rollo est\u00e1ndar 72 x 80 cm - Reforzado - italianacontenitori.com","og_description":"Contenedor rodante est\u00e1ndar con base reforzada. Robustez y estabilidad para mercanc\u00edas pesadas, ideal para lavander\u00edas, industria, gran distribuci\u00f3n. Carga m\u00e1xima: 600 kg.","og_url":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/","og_site_name":"italianacontenitori.com","article_modified_time":"2026-07-02T08:18:21+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/12\/ROLR0050H4R0-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/","url":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/","name":"Contenedor de rollo est\u00e1ndar 72 x 80 cm - Reforzado - italianacontenitori.com","isPartOf":{"@id":"https:\/\/www.italianacontenitori.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/#primaryimage"},"image":{"@id":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/12\/ROLR0050H4R0-1.png","datePublished":"2020-12-11T14:18:06+00:00","dateModified":"2026-07-02T08:18:21+00:00","description":"Contenedor rodante est\u00e1ndar con base reforzada. Robustez y estabilidad para mercanc\u00edas pesadas, ideal para lavander\u00edas, industria, gran distribuci\u00f3n. Carga m\u00e1xima: 600 kg.","breadcrumb":{"@id":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/#primaryimage","url":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/12\/ROLR0050H4R0-1.png","contentUrl":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/12\/ROLR0050H4R0-1.png","width":1024,"height":1024,"caption":"Contenedor rodante est\u00e1ndar con base reforzada. 72x80 cm. Disponible con 2 lados, 3 lados y 4 lados con solapa. Capacidad de carga 600 kg."},{"@type":"BreadcrumbList","@id":"https:\/\/www.italianacontenitori.com\/es\/producto\/roll-72-x-80-cm-base-renforzada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italianacontenitori.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo Espa\u00f1ol","item":"https:\/\/www.italianacontenitori.com\/es\/cataogo-es\/"},{"@type":"ListItem","position":3,"name":"Contenedor de rollo est\u00e1ndar 72 x 80 cm &#8211; Reforzado"}]},{"@type":"WebSite","@id":"https:\/\/www.italianacontenitori.com\/es\/#website","url":"https:\/\/www.italianacontenitori.com\/es\/","name":"italianacontenitori.com","description":"Produzione di contenitori industriali e roll container","publisher":{"@id":"https:\/\/www.italianacontenitori.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italianacontenitori.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.italianacontenitori.com\/es\/#organization","name":"Italiana Contenitori s.r.l.","alternateName":"IC","url":"https:\/\/www.italianacontenitori.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.italianacontenitori.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/11\/cropped-Logo-Italiana-Contenitori_favicon.jpg","contentUrl":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/11\/cropped-Logo-Italiana-Contenitori_favicon.jpg","width":512,"height":512,"caption":"Italiana Contenitori s.r.l."},"image":{"@id":"https:\/\/www.italianacontenitori.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/product\/241343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/comments?post=241343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/media\/240273"}],"wp:attachment":[{"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/media?parent=241343"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/product_brand?post=241343"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/product_cat?post=241343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.italianacontenitori.com\/es\/wp-json\/wp\/v2\/product_tag?post=241343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}