{"id":2058,"count":5,"description":"","link":"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/","name":"Comment il est fabriqu\u00e9","slug":"comment-il-est-fabrique","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come vengono prodotti Roll container e Contenitori industriali<\/title>\n<meta name=\"description\" content=\"Approfondimenti tecnici su materiali, assemblaggio, tecniche costruttive e automazione nella produzione di roll container e contenitori in rete metallica.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come vengono prodotti Roll container e Contenitori industriali\" \/>\n<meta property=\"og:description\" content=\"Approfondimenti tecnici su materiali, assemblaggio, tecniche costruttive e automazione nella produzione di roll container e contenitori in rete metallica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/\" \/>\n<meta property=\"og:site_name\" content=\"italianacontenitori.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/categoria\\\/comment-il-est-fabrique\\\/\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/categoria\\\/comment-il-est-fabrique\\\/\",\"name\":\"Come vengono prodotti Roll container e Contenitori industriali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/#website\"},\"description\":\"Approfondimenti tecnici su materiali, assemblaggio, tecniche costruttive e automazione nella produzione di roll container e contenitori in rete metallica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/categoria\\\/comment-il-est-fabrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/categoria\\\/comment-il-est-fabrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment il est fabriqu\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/\",\"name\":\"italianacontenitori.com\",\"description\":\"Produzione di contenitori industriali e roll container\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/#organization\",\"name\":\"Italiana Contenitori s.r.l.\",\"alternateName\":\"IC\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-Logo-Italiana-Contenitori_favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.italianacontenitori.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-Logo-Italiana-Contenitori_favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Italiana Contenitori s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italianacontenitori.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come vengono prodotti Roll container e Contenitori industriali","description":"Approfondimenti tecnici su materiali, assemblaggio, tecniche costruttive e automazione nella produzione di roll container e contenitori in rete metallica.","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Come vengono prodotti Roll container e Contenitori industriali","og_description":"Approfondimenti tecnici su materiali, assemblaggio, tecniche costruttive e automazione nella produzione di roll container e contenitori in rete metallica.","og_url":"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/","og_site_name":"italianacontenitori.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/","url":"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/","name":"Come vengono prodotti Roll container e Contenitori industriali","isPartOf":{"@id":"https:\/\/www.italianacontenitori.com\/fr\/#website"},"description":"Approfondimenti tecnici su materiali, assemblaggio, tecniche costruttive e automazione nella produzione di roll container e contenitori in rete metallica.","breadcrumb":{"@id":"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italianacontenitori.com\/fr\/categoria\/comment-il-est-fabrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italianacontenitori.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment il est fabriqu\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.italianacontenitori.com\/fr\/#website","url":"https:\/\/www.italianacontenitori.com\/fr\/","name":"italianacontenitori.com","description":"Produzione di contenitori industriali e roll container","publisher":{"@id":"https:\/\/www.italianacontenitori.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italianacontenitori.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.italianacontenitori.com\/fr\/#organization","name":"Italiana Contenitori s.r.l.","alternateName":"IC","url":"https:\/\/www.italianacontenitori.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.italianacontenitori.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/11\/cropped-Logo-Italiana-Contenitori_favicon.jpg","contentUrl":"https:\/\/www.italianacontenitori.com\/wp-content\/uploads\/2020\/11\/cropped-Logo-Italiana-Contenitori_favicon.jpg","width":512,"height":512,"caption":"Italiana Contenitori s.r.l."},"image":{"@id":"https:\/\/www.italianacontenitori.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.italianacontenitori.com\/fr\/wp-json\/wp\/v2\/categories\/2058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italianacontenitori.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.italianacontenitori.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.italianacontenitori.com\/fr\/wp-json\/wp\/v2\/posts?categories=2058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}